{"id":38,"count":2,"description":"","link":"https:\/\/coffeealchemy.iskandersun.com\/it\/category\/costa-rica\/","name":"Costa Rica","slug":"costa-rica","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Costa Rica Archives - CoffeeAlchemy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coffeealchemy.iskandersun.com\/it\/category\/costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costa Rica Archives - CoffeeAlchemy\" \/>\n<meta property=\"og:site_name\" content=\"CoffeeAlchemy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Home-coffee.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/category\\\/costa-rica\\\/\",\"url\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/category\\\/costa-rica\\\/\",\"name\":\"Costa Rica Archives - CoffeeAlchemy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/category\\\/costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/category\\\/costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/#website\",\"url\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/\",\"name\":\"CoffeeAlchemy\",\"description\":\"CoffeeAlchemy\",\"publisher\":{\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/#\\\/schema\\\/person\\\/9b22d10cc439edad7067b2ffaf3c2976\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/#\\\/schema\\\/person\\\/9b22d10cc439edad7067b2ffaf3c2976\",\"name\":\"J. A. Ampudia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screen-Shot-2025-01-20-at-11.17.56-AM.png\",\"url\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screen-Shot-2025-01-20-at-11.17.56-AM.png\",\"contentUrl\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screen-Shot-2025-01-20-at-11.17.56-AM.png\",\"width\":640,\"height\":642,\"caption\":\"J. A. Ampudia\"},\"logo\":{\"@id\":\"https:\\\/\\\/coffeealchemy.iskandersun.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screen-Shot-2025-01-20-at-11.17.56-AM.png\"},\"sameAs\":[\"https:\\\/\\\/coffeealchemy.iskandersun.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costa Rica Archives - CoffeeAlchemy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coffeealchemy.iskandersun.com\/it\/category\/costa-rica\/","og_locale":"it_IT","og_type":"article","og_title":"Costa Rica Archives - CoffeeAlchemy","og_site_name":"CoffeeAlchemy","og_image":[{"width":1920,"height":1076,"url":"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Home-coffee.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coffeealchemy.iskandersun.com\/category\/costa-rica\/","url":"https:\/\/coffeealchemy.iskandersun.com\/category\/costa-rica\/","name":"Costa Rica Archives - CoffeeAlchemy","isPartOf":{"@id":"https:\/\/coffeealchemy.iskandersun.com\/#website"},"breadcrumb":{"@id":"https:\/\/coffeealchemy.iskandersun.com\/category\/costa-rica\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/coffeealchemy.iskandersun.com\/category\/costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coffeealchemy.iskandersun.com\/"},{"@type":"ListItem","position":2,"name":"Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/coffeealchemy.iskandersun.com\/#website","url":"https:\/\/coffeealchemy.iskandersun.com\/","name":"CoffeeAlchemy","description":"CoffeeAlchemy","publisher":{"@id":"https:\/\/coffeealchemy.iskandersun.com\/#\/schema\/person\/9b22d10cc439edad7067b2ffaf3c2976"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coffeealchemy.iskandersun.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/coffeealchemy.iskandersun.com\/#\/schema\/person\/9b22d10cc439edad7067b2ffaf3c2976","name":"J. A. Ampudia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2025-01-20-at-11.17.56-AM.png","url":"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2025-01-20-at-11.17.56-AM.png","contentUrl":"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2025-01-20-at-11.17.56-AM.png","width":640,"height":642,"caption":"J. A. Ampudia"},"logo":{"@id":"https:\/\/coffeealchemy.iskandersun.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2025-01-20-at-11.17.56-AM.png"},"sameAs":["https:\/\/coffeealchemy.iskandersun.com"]}]}},"_links":{"self":[{"href":"https:\/\/coffeealchemy.iskandersun.com\/it\/wp-json\/wp\/v2\/categories\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coffeealchemy.iskandersun.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/coffeealchemy.iskandersun.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/coffeealchemy.iskandersun.com\/it\/wp-json\/wp\/v2\/posts?categories=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}